{"id":44964,"date":"2025-09-02T11:23:25","date_gmt":"2025-09-02T09:23:25","guid":{"rendered":"https:\/\/fermesinsac.com\/?post_type=product&#038;p=44964"},"modified":"2026-04-05T19:09:35","modified_gmt":"2026-04-05T17:09:35","slug":"petillant-de-peche-carton-de-6-bouteilles","status":"publish","type":"product","link":"https:\/\/fermesinsac.com\/af\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/","title":{"rendered":"Boisson P\u00e9tillante de P\u00eache carton de 6 bouteilles"},"content":{"rendered":"<div data-elementor-type=\"product-post\" data-elementor-id=\"44964\" class=\"elementor elementor-44964\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37e306cf e-flex e-con-boxed e-con e-parent\" data-id=\"37e306cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-692c442f elementor-widget elementor-widget-text-editor\" data-id=\"692c442f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNos boisson P\u00e9tillant aux p\u00eaches sont sans alcool, r\u00e9colt\u00e9s et infus\u00e9s avec du sucre de canne bio et du citron bio. Comme les limonade a l&#8217;ancienne avec une fermentation naturelle s&#8217;op\u00e8re ce qui lui conf\u00e8re de fines bulles. Un l\u00e9ger d\u00e9p\u00f4t se forme naturellement. <br>Ne pas agiter avant l ouverture. Aucun conservateur, aucun colorant. <br><br>Nos p\u00eachers sont men\u00e9s en gobelet avec une forme d arbre naturel et de la taille douce en hiver, nous r\u00e9coltons de juin \u00e0 octobre et c est \u00e0 cette p\u00e9riode uniquement que nous faisons notre P\u00e9tillant. Ce produit de saison est sain, a un parfum d\u00e9licat et comporte toutes les propri\u00e9t\u00e9s b\u00e9n\u00e9fiques de la P\u00eache: am\u00e9liore la digestion, renforcent le syst\u00e8me immunitaire, favorise la perte de poids, et a des propri\u00e9t\u00e9s anti-inflammatoires. <br>Tous nos produits sont fabriqu\u00e9s et conditionn\u00e9s a la ferme Sinsac. <br><br>Ce n&#8217;est pas du Kombucha, ce n&#8217;est pas du K\u00e9fir, c\u2019est de la fermentation naturelle de fleurs, de plantes et de fruits. Les bulles se forment petit \u00e0 petit gr\u00e2ces aux enzymes contenus naturellement dans les fleurs, les plantes, les fruits et au sucre de canne biologique, elles sont fines et l\u00e9g\u00e8res. Bon pour la flore intestinale, cet P\u00e9tillant\u00a0 contient 37 grs de sucre par bouteille de 75 cl ce qui lui conf\u00e8re de la gourmandise sans exc\u00e8s de sucre. Les P\u00e9tillants\u00a0sont pr\u00eats \u00e0 d\u00e9guster avec des gla\u00e7ons ou en cocktail. Ils ne contiennent pas d alcool et sont rafraichissantes. Chaque fleur et plante a ses propres propri\u00e9t\u00e9s b\u00e9n\u00e9fiques. Cette boisson artisanale ne contient ni colorant, ni conservateur, ni Co2 ajout\u00e9 et se conserve ferm\u00e9 pendant 6 mois. Une fois ouverte, reposer la capsule sur la bouteille, mettre au frais et \u00e0 consommer rapidement. Les fleurs, les plantes et les fruits sont cultiv\u00e9es sur nos terres en agro-\u00e9cologie: une terre pleine de vie. Nous suivons les saisons pour vous proposer des P\u00e9tillants\u00a0atypiques et rafraichissants. Vous trouverez notamment un P\u00e9tillant\u00a0aux fleurs de Mimosa, \u00e0 la verveine citronn\u00e9e, aux fleurs de sureau, au Shiso cette plante japonaise d\u00e9licate, \u00e0 la p\u00eache. Nous d\u00e9veloppons notre gamme toute l&#8217;ann\u00e9e pour vous surprendre.<br>Nos l\u00e9gumes et fruits sont en cultiv\u00e9s sur sol vivant sans engrais chimiques, sans pesticides et dans le respect de la biodiversit\u00e9e<br><br>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4fbeb6 e-flex e-con-boxed e-con e-parent\" data-id=\"f4fbeb6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1549b1 elementor-widget elementor-widget-lte-products\" data-id=\"b1549b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"lte-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"lte-cols-xl-4 lte-cols-lg-4 lte-cols-md-4 lte-cols-sm-3 lte-cols-ms-3 lte-cols-xs-1 lte-padding-no woocommerce lte-products-sc lte-product-style-default lte-wc-wrapper\"><ul class=\"products columns-128 lte-products-sc lte-products-sc-simple\">\t\t\t<li class=\"product post-42807 type-product status-publish has-post-thumbnail product_cat-arbres-fruitiers product_tag-pommier-varieteancienne-bio-fruitiers-arbresaplanter first instock virtual taxable purchasable product-type-simple\">\r\n\t\t\t\t<div class=\"lte-item\"><div class=\"lte-image\"><div class=\"lte-buttons-wrapper\"><a href=\"\/af\/wp-json\/wp\/v2\/product\/44964?add-to-cart=42807\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_42807\" data-quantity=\"1\" class=\"lte-btn btn-xs btn-main color-hover-black product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"42807\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Pommier&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pommier&rdquo; has been added to your cart\" role=\"lte-btn btn-xs btn-main color-hover-black\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"lte-btn-inner\"><span class=\"lte-btn-before\"><\/span>Add to cart<span class=\"lte-btn-after\"><\/span><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_42807\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<a href=\"https:\/\/fermesinsac.com\/af\/shop\/compensation-c02\/arbres-fruitiers\/pommier\/\" class=\"lte-wc-view\"><\/a><\/div><a href=\"https:\/\/fermesinsac.com\/af\/shop\/compensation-c02\/arbres-fruitiers\/pommier\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img fetchpriority=\"high\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-480x640.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Pommier\" srcset=\"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-480x640.webp 480w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-225x300.webp 225w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-768x1024.webp 768w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-1152x1536.webp 1152w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-375x500.webp 375w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-500x667.webp 500w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-75x100.webp 75w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-450x600.webp 450w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-938x1250.webp 938w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975-600x800.webp 600w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/IMG_2975.webp 1200w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/a><\/div><div class=\"lte-item-descr\"><a href=\"https:\/\/fermesinsac.com\/af\/shop\/compensation-c02\/arbres-fruitiers\/pommier\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Pommier<\/h2><\/a><div class=\"lte-excerpt\">Pommier de vari\u00e9t\u00e9 anciennes en fonction des disponibilit\u00e9s de notre p\u00e9pini\u00e9riste.\nRacines nues sur fut de &hellip;<\/div>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n<div class=\"lte-wc-bottom-btns\"><a href=\"\/af\/wp-json\/wp\/v2\/product\/44964?add-to-cart=42807\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_42807\" data-quantity=\"1\" class=\"lte-btn btn-xs btn-main color-hover-black product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"42807\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Pommier&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pommier&rdquo; has been added to your cart\" role=\"lte-btn btn-xs btn-main color-hover-black\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"lte-btn-inner\"><span class=\"lte-btn-before\"><\/span>Add to cart<span class=\"lte-btn-after\"><\/span><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_42807\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div><\/div>\n\t\t<\/div>\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"product post-43705 type-product status-publish has-post-thumbnail product_cat-arbres-communs product_tag-chataignierchataignearbrecommunbio  instock virtual taxable purchasable product-type-simple\">\r\n\t\t\t\t<div class=\"lte-item\"><div class=\"lte-image\"><div class=\"lte-buttons-wrapper\"><a href=\"\/af\/wp-json\/wp\/v2\/product\/44964?add-to-cart=43705\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_43705\" data-quantity=\"1\" class=\"lte-btn btn-xs btn-main color-hover-black product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"43705\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Ch\u00e2taignier&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Ch\u00e2taignier&rdquo; has been added to your cart\" role=\"lte-btn btn-xs btn-main color-hover-black\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"lte-btn-inner\"><span class=\"lte-btn-before\"><\/span>Add to cart<span class=\"lte-btn-after\"><\/span><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_43705\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<a href=\"https:\/\/fermesinsac.com\/af\/shop\/compensation-c02\/arbres-communs\/chataignier\/\" class=\"lte-wc-view\"><\/a><\/div><a href=\"https:\/\/fermesinsac.com\/af\/shop\/compensation-c02\/arbres-communs\/chataignier\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"474\" height=\"355\" src=\"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Chataignier.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ch\u00e2taignier\" srcset=\"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Chataignier.webp 474w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Chataignier-300x225.webp 300w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Chataignier-100x75.webp 100w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Chataignier-450x337.webp 450w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><\/div><div class=\"lte-item-descr\"><a href=\"https:\/\/fermesinsac.com\/af\/shop\/compensation-c02\/arbres-communs\/chataignier\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Ch\u00e2taignier<\/h2><\/a><div class=\"lte-excerpt\">Ch\u00e2taignier Castanea Sativa.\nRacines nues sur f\u00fbt de 18 \u00e0 24 mois pour une meilleure reprise &hellip;<\/div>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n<div class=\"lte-wc-bottom-btns\"><a href=\"\/af\/wp-json\/wp\/v2\/product\/44964?add-to-cart=43705\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_43705\" data-quantity=\"1\" class=\"lte-btn btn-xs btn-main color-hover-black product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"43705\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Ch\u00e2taignier&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Ch\u00e2taignier&rdquo; has been added to your cart\" role=\"lte-btn btn-xs btn-main color-hover-black\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"lte-btn-inner\"><span class=\"lte-btn-before\"><\/span>Add to cart<span class=\"lte-btn-after\"><\/span><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_43705\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div><\/div>\n\t\t<\/div>\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"product post-43708 type-product status-publish has-post-thumbnail product_cat-arbres-communs product_tag-hetrearbrecommunbioarbre  instock virtual taxable purchasable product-type-simple\">\r\n\t\t\t\t<div class=\"lte-item\"><div class=\"lte-image\"><div class=\"lte-buttons-wrapper\"><a href=\"\/af\/wp-json\/wp\/v2\/product\/44964?add-to-cart=43708\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_43708\" data-quantity=\"1\" class=\"lte-btn btn-xs btn-main color-hover-black product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"43708\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;H\u00eatre&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;H\u00eatre&rdquo; has been added to your cart\" role=\"lte-btn btn-xs btn-main color-hover-black\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"lte-btn-inner\"><span class=\"lte-btn-before\"><\/span>Add to cart<span class=\"lte-btn-after\"><\/span><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_43708\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<a href=\"https:\/\/fermesinsac.com\/af\/shop\/compensation-c02\/arbres-communs\/hetre\/\" class=\"lte-wc-view\"><\/a><\/div><a href=\"https:\/\/fermesinsac.com\/af\/shop\/compensation-c02\/arbres-communs\/hetre\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"474\" height=\"632\" src=\"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/hetre.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"H\u00eatre\" srcset=\"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/hetre.webp 474w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/hetre-225x300.webp 225w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/hetre-375x500.webp 375w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/hetre-75x100.webp 75w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/hetre-450x600.webp 450w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><\/div><div class=\"lte-item-descr\"><a href=\"https:\/\/fermesinsac.com\/af\/shop\/compensation-c02\/arbres-communs\/hetre\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">H\u00eatre<\/h2><\/a><div class=\"lte-excerpt\">H\u00eatre commun.\nRacines nues sur f\u00fbt de 18 \u00e0 24 mois pour une meilleure reprise \u00e0 &hellip;<\/div>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n<div class=\"lte-wc-bottom-btns\"><a href=\"\/af\/wp-json\/wp\/v2\/product\/44964?add-to-cart=43708\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_43708\" data-quantity=\"1\" class=\"lte-btn btn-xs btn-main color-hover-black product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"43708\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;H\u00eatre&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;H\u00eatre&rdquo; has been added to your cart\" role=\"lte-btn btn-xs btn-main color-hover-black\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"lte-btn-inner\"><span class=\"lte-btn-before\"><\/span>Add to cart<span class=\"lte-btn-after\"><\/span><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_43708\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div><\/div>\n\t\t<\/div>\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t<li class=\"product post-43712 type-product status-publish has-post-thumbnail product_cat-haie-champetre product_tag-haieoiseauxauxiliairesbio  instock virtual taxable purchasable product-type-simple\">\r\n\t\t\t\t<div class=\"lte-item\"><div class=\"lte-image\"><div class=\"lte-buttons-wrapper\"><a href=\"\/af\/wp-json\/wp\/v2\/product\/44964?add-to-cart=43712\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_43712\" data-quantity=\"1\" class=\"lte-btn btn-xs btn-main color-hover-black product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"43712\" data-product_sku=\"haie-ecologique-pour-oiseaux-et-auxilliaires\" aria-label=\"Add to cart: &ldquo;Haie \u00e9cologique pour oiseaux et auxiliaires&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Haie \u00e9cologique pour oiseaux et auxiliaires&rdquo; has been added to your cart\" role=\"lte-btn btn-xs btn-main color-hover-black\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"lte-btn-inner\"><span class=\"lte-btn-before\"><\/span>Add to cart<span class=\"lte-btn-after\"><\/span><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_43712\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<a href=\"https:\/\/fermesinsac.com\/af\/shop\/haie-champetre\/haie-ecologique-pour-oiseaux-et-auxiliaires\/\" class=\"lte-wc-view\"><\/a><\/div><a href=\"https:\/\/fermesinsac.com\/af\/shop\/haie-champetre\/haie-ecologique-pour-oiseaux-et-auxiliaires\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"294\" src=\"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Haie-champetre.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Haie \u00e9cologique pour oiseaux et auxiliaires\" srcset=\"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Haie-champetre.webp 474w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Haie-champetre-300x186.webp 300w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Haie-champetre-100x62.webp 100w, https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/02\/Haie-champetre-450x279.webp 450w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><\/div><div class=\"lte-item-descr\"><a href=\"https:\/\/fermesinsac.com\/af\/shop\/haie-champetre\/haie-ecologique-pour-oiseaux-et-auxiliaires\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Haie \u00e9cologique pour oiseaux et auxiliaires<\/h2><\/a><div class=\"lte-excerpt\">Haie \u00e9cologique pour oiseaux et auxiliaires comprenant 20 esp\u00e8ces d&#8217;arbustes utiles \u00e0 la faune et &hellip;<\/div>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>360,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n<div class=\"lte-wc-bottom-btns\"><a href=\"\/af\/wp-json\/wp\/v2\/product\/44964?add-to-cart=43712\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_43712\" data-quantity=\"1\" class=\"lte-btn btn-xs btn-main color-hover-black product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"43712\" data-product_sku=\"haie-ecologique-pour-oiseaux-et-auxilliaires\" aria-label=\"Add to cart: &ldquo;Haie \u00e9cologique pour oiseaux et auxiliaires&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Haie \u00e9cologique pour oiseaux et auxiliaires&rdquo; has been added to your cart\" role=\"lte-btn btn-xs btn-main color-hover-black\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"lte-btn-inner\"><span class=\"lte-btn-before\"><\/span>Add to cart<span class=\"lte-btn-after\"><\/span><\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_43712\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div><\/div>\n\t\t<\/div>\t\t\t<\/li>\r\n\t\t\t\t\t<\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"woocommerce-product-details__short-description\">\n<p>Ce boisson p\u00e9tillante de verveine est compos\u00e9 de:<\/p>\n<p>P\u00eaches cultiv\u00e9es sans engrais, sans pesticides, jus de citron*, sucre de canne*, eau<\/p>\n<p>*produits issus de l agriculture biologique<\/p><\/div>","protected":false},"featured_media":45238,"comment_status":"open","ping_status":"closed","template":"","meta":{"_price":"57","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[722],"product_tag":[733],"class_list":["post-44964","product","type-product","status-publish","has-post-thumbnail","product_cat-boissons","product_tag-bio-petillant-peche-naturel-sansalcool","","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boisson P\u00e9tillante de P\u00eache carton de 6 bouteilles - Ferme Sinsac<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fermesinsac.com\/af\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boisson P\u00e9tillante de P\u00eache carton de 6 bouteilles - Ferme Sinsac\" \/>\n<meta property=\"og:description\" content=\"Ce boisson p\u00e9tillante de verveine est compos\u00e9 de:P\u00eaches cultiv\u00e9es sans engrais, sans pesticides, jus de citron*, sucre de canne*, eau*produits issus de l agriculture biologique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fermesinsac.com\/af\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/\" \/>\n<meta property=\"og:site_name\" content=\"Ferme Sinsac\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fermebiosinsac\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-05T17:09:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fermesinsac.com\/wp-content\/uploads\/2026\/03\/petillante-de-peche-limonade-vermentation-naturelle-sans-pesticides-ferme-sinsac.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/shop\\\/boissons\\\/petillant-de-peche-carton-de-6-bouteilles\\\/\",\"url\":\"https:\\\/\\\/fermesinsac.com\\\/shop\\\/boissons\\\/petillant-de-peche-carton-de-6-bouteilles\\\/\",\"name\":\"Boisson P\u00e9tillante de P\u00eache carton de 6 bouteilles - Ferme Sinsac\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/shop\\\/boissons\\\/petillant-de-peche-carton-de-6-bouteilles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/shop\\\/boissons\\\/petillant-de-peche-carton-de-6-bouteilles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fermesinsac.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/petillante-de-peche-limonade-vermentation-naturelle-sans-pesticides-ferme-sinsac.jpeg\",\"datePublished\":\"2025-09-02T09:23:25+00:00\",\"dateModified\":\"2026-04-05T17:09:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/shop\\\/boissons\\\/petillant-de-peche-carton-de-6-bouteilles\\\/#breadcrumb\"},\"inLanguage\":\"af-ZA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fermesinsac.com\\\/shop\\\/boissons\\\/petillant-de-peche-carton-de-6-bouteilles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"af-ZA\",\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/shop\\\/boissons\\\/petillant-de-peche-carton-de-6-bouteilles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fermesinsac.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/petillante-de-peche-limonade-vermentation-naturelle-sans-pesticides-ferme-sinsac.jpeg\",\"contentUrl\":\"https:\\\/\\\/fermesinsac.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/petillante-de-peche-limonade-vermentation-naturelle-sans-pesticides-ferme-sinsac.jpeg\",\"width\":800,\"height\":600,\"caption\":\"boisson petillante de peche limonade fermentation naturelle cocktail sans alcool limonade sans pesticides ferme sinsac\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/shop\\\/boissons\\\/petillant-de-peche-carton-de-6-bouteilles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fermesinsac.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/fermesinsac.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Boisson P\u00e9tillante de P\u00eache carton de 6 bouteilles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/#website\",\"url\":\"https:\\\/\\\/fermesinsac.com\\\/\",\"name\":\"Ferme Sinsac\",\"description\":\"la biodiversit\u00e9 avant tout\",\"publisher\":{\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fermesinsac.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"af-ZA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/#organization\",\"name\":\"Ferme Sinsac\",\"url\":\"https:\\\/\\\/fermesinsac.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"af-ZA\",\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fermesinsac.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-logo-ferme-sinsac-klein.webp\",\"contentUrl\":\"https:\\\/\\\/fermesinsac.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-logo-ferme-sinsac-klein.webp\",\"width\":512,\"height\":512,\"caption\":\"Ferme Sinsac\"},\"image\":{\"@id\":\"https:\\\/\\\/fermesinsac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fermebiosinsac\",\"https:\\\/\\\/www.tiktok.com\\\/@fermesinsac?lang=nl-NL\",\"https:\\\/\\\/www.instagram.com\\\/fermebiosinsac\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/31423500\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boisson P\u00e9tillante de P\u00eache carton de 6 bouteilles - Ferme Sinsac","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fermesinsac.com\/af\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/","og_locale":"en_US","og_type":"article","og_title":"Boisson P\u00e9tillante de P\u00eache carton de 6 bouteilles - Ferme Sinsac","og_description":"Ce boisson p\u00e9tillante de verveine est compos\u00e9 de:P\u00eaches cultiv\u00e9es sans engrais, sans pesticides, jus de citron*, sucre de canne*, eau*produits issus de l agriculture biologique","og_url":"https:\/\/fermesinsac.com\/af\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/","og_site_name":"Ferme Sinsac","article_publisher":"https:\/\/www.facebook.com\/fermebiosinsac","article_modified_time":"2026-04-05T17:09:35+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/fermesinsac.com\/wp-content\/uploads\/2026\/03\/petillante-de-peche-limonade-vermentation-naturelle-sans-pesticides-ferme-sinsac.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fermesinsac.com\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/","url":"https:\/\/fermesinsac.com\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/","name":"Boisson P\u00e9tillante de P\u00eache carton de 6 bouteilles - Ferme Sinsac","isPartOf":{"@id":"https:\/\/fermesinsac.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fermesinsac.com\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/#primaryimage"},"image":{"@id":"https:\/\/fermesinsac.com\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/#primaryimage"},"thumbnailUrl":"https:\/\/fermesinsac.com\/wp-content\/uploads\/2026\/03\/petillante-de-peche-limonade-vermentation-naturelle-sans-pesticides-ferme-sinsac.jpeg","datePublished":"2025-09-02T09:23:25+00:00","dateModified":"2026-04-05T17:09:35+00:00","breadcrumb":{"@id":"https:\/\/fermesinsac.com\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/#breadcrumb"},"inLanguage":"af-ZA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fermesinsac.com\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/"]}]},{"@type":"ImageObject","inLanguage":"af-ZA","@id":"https:\/\/fermesinsac.com\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/#primaryimage","url":"https:\/\/fermesinsac.com\/wp-content\/uploads\/2026\/03\/petillante-de-peche-limonade-vermentation-naturelle-sans-pesticides-ferme-sinsac.jpeg","contentUrl":"https:\/\/fermesinsac.com\/wp-content\/uploads\/2026\/03\/petillante-de-peche-limonade-vermentation-naturelle-sans-pesticides-ferme-sinsac.jpeg","width":800,"height":600,"caption":"boisson petillante de peche limonade fermentation naturelle cocktail sans alcool limonade sans pesticides ferme sinsac"},{"@type":"BreadcrumbList","@id":"https:\/\/fermesinsac.com\/shop\/boissons\/petillant-de-peche-carton-de-6-bouteilles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fermesinsac.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/fermesinsac.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Boisson P\u00e9tillante de P\u00eache carton de 6 bouteilles"}]},{"@type":"WebSite","@id":"https:\/\/fermesinsac.com\/#website","url":"https:\/\/fermesinsac.com\/","name":"Ferme Sinsac","description":"la biodiversit\u00e9 avant tout","publisher":{"@id":"https:\/\/fermesinsac.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fermesinsac.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"af-ZA"},{"@type":"Organization","@id":"https:\/\/fermesinsac.com\/#organization","name":"Ferme Sinsac","url":"https:\/\/fermesinsac.com\/","logo":{"@type":"ImageObject","inLanguage":"af-ZA","@id":"https:\/\/fermesinsac.com\/#\/schema\/logo\/image\/","url":"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/cropped-logo-ferme-sinsac-klein.webp","contentUrl":"https:\/\/fermesinsac.com\/wp-content\/uploads\/2025\/01\/cropped-logo-ferme-sinsac-klein.webp","width":512,"height":512,"caption":"Ferme Sinsac"},"image":{"@id":"https:\/\/fermesinsac.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fermebiosinsac","https:\/\/www.tiktok.com\/@fermesinsac?lang=nl-NL","https:\/\/www.instagram.com\/fermebiosinsac\/","https:\/\/www.linkedin.com\/company\/31423500\/"]}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/product\/44964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/comments?post=44964"}],"version-history":[{"count":6,"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/product\/44964\/revisions"}],"predecessor-version":[{"id":45254,"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/product\/44964\/revisions\/45254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/media\/45238"}],"wp:attachment":[{"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/media?parent=44964"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/product_brand?post=44964"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/product_cat?post=44964"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fermesinsac.com\/af\/wp-json\/wp\/v2\/product_tag?post=44964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}